{"id":1318,"date":"2012-08-30T18:31:31","date_gmt":"2012-08-30T18:31:31","guid":{"rendered":"https:\/\/drugpolicy.ca\/?p=1318"},"modified":"2015-04-04T20:23:05","modified_gmt":"2015-04-04T20:23:05","slug":"quest-ce-que-la-naloxone","status":"publish","type":"post","link":"https:\/\/webdisk.drugpolicy.ca\/fr\/quest-ce-que-la-naloxone\/","title":{"rendered":"Qu\u2019est-ce que la naloxone?"},"content":{"rendered":"<p>La naloxone est un compos\u00e9 chimique s\u00e9curitaire et tr\u00e8s efficace qui inverse les effets des opiac\u00e9s comme l\u2019h\u00e9ro\u00efne. Depuis 40 ans, elle est utilis\u00e9e dans des milieux cliniques comme traitement d\u2019urgence contre les surdoses d\u2019opiac\u00e9s. Aux \u00c9.-U. et en Europe, les programmes \u00ab\u00a0Take Home Naloxone\u00a0\u00bb ont \u00e9t\u00e9 associ\u00e9s \u00e0 des r\u00e9ductions de jusqu\u2019\u00e0 34\u00a0% des d\u00e9c\u00e8s li\u00e9s aux drogues[1]. L\u2019utilisation de la naloxone au Canada est autoris\u00e9e depuis plus de 40 ans, et elle figure \u00e0 la Liste mod\u00e8le de l\u2019OMS des m\u00e9dicaments essentiels. La naloxone ne peut faire l\u2019objet d\u2019abus \u2013 en l\u2019absence de narcotiques, elle ne pr\u00e9sente essentiellement aucune activit\u00e9 pharmacologique. La naloxone ne fonctionne qu\u2019avec les drogues de la famille des opiac\u00e9s\/opio\u00efdes \u2013 elle n\u2019est <strong>pas<\/strong> efficace pour les surdoses d\u2019autres drogues comme la coca\u00efne.<\/p>\n<p><strong>Comment la naloxone peut-elle r\u00e9duire le nombre de d\u00e9c\u00e8s li\u00e9s aux drogues?<\/strong><\/p>\n<p>La naloxone peut jouer un r\u00f4le majeur dans la pr\u00e9vention des d\u00e9c\u00e8s \u2013 surtout si elle peut \u00eatre administr\u00e9e \u00e0 une personne en surdose aussi t\u00f4t que possible. Afin de maximiser l\u2019effet de la naloxone sur les d\u00e9c\u00e8s li\u00e9s aux drogues, il faut que la naloxone soit disponible sur les lieux de la surdose <em>avant<\/em> l\u2019arriv\u00e9e de l\u2019aide sp\u00e9cialis\u00e9e. Ce qui veut dire que la naloxone doit \u00eatre disponible pour les membres de la communaut\u00e9, aux fins d\u2019utilisation d\u2019urgence. Les programmes \u00ab\u00a0Take Home Naloxone\u00a0\u00bb ont \u00e9t\u00e9 li\u00e9s \u00e0 des r\u00e9ductions de jusqu\u2019\u00e0 34\u00a0% des d\u00e9c\u00e8s li\u00e9s aux drogues[2].<\/p>\n<p>L\u2019acc\u00e8s \u00e0 la naloxone varie autour du monde, notamment les doses \u00e0 apporter (take-home) pour les personnes qui utilisent des drogues illicites en Europe, en Australie, de m\u00eame qu\u2019\u00e0 Edmonton et Toronto. L\u2019\u00c9cosse a instaur\u00e9 une National Patient Group Directive en ao\u00fbt 2010 pour faciliter le d\u00e9veloppement de programmes de naloxone pour apporter. Les Patient Group Directives (PGD) permettent que la naloxone soit prescrite par des infirmi\u00e8res et des pharmaciens comp\u00e9tents. En \u00c9cosse, chaque personne lib\u00e9r\u00e9e d\u2019une prison et \u00e0 risque de surdose re\u00e7oit une formation et une trousse de naloxone[3]. La naloxone est en vente libre \u00e0 Turin, en Italie. Il y a plus de 180 programmes r\u00e9ussis de naloxone pour apporter aux \u00c9tats-Unis, comme le <a href=\"http:\/\/www.projectlazarus.org\/\">Project Lazarus<\/a> de Caroline du Nord, qui a contribu\u00e9 \u00e0 distribuer de la naloxone aux personnes qui sont \u00e0 risque \u00e0 cause des opiac\u00e9s prescrits[4].<\/p>\n<p>Au Canada, la naloxone est contr\u00f4l\u00e9e \u00e0 titre de m\u00e9dicament sur ordonnance (MSO) en vertu de l\u2019annexe F du R\u00e8glement de la <em>Loi sur les aliments et drogues<\/em>. Elle est prescrite par les m\u00e9decins \u00e0 des patients d\u00e9sign\u00e9s nomm\u00e9ment seulement, qui sont jug\u00e9s \u00e0 risque d\u2019une surdose d\u2019opiac\u00e9s. La disponibilit\u00e9 de la naloxone est \u00e9galement soumise \u00e0 la l\u00e9gislation provinciale r\u00e9gissant les pharmacies ainsi qu\u2019aux organisations professionnelles comme les coll\u00e8ges provinciaux de m\u00e9decins et chirurgiens.<\/p>\n<p>La recherche a constat\u00e9 que la disponibilit\u00e9 de la naloxone n\u2019augmente pas l\u2019utilisation des opio\u00efdes. Des programmes ont remarqu\u00e9 que former des gens \u00e0 administrer un m\u00e9dicament qui sauve des vies est une exp\u00e9rience qui change une vie.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div><br clear=\"all\" \/><\/p>\n<hr align=\"left\" size=\"1\" width=\"33%\" \/>\n<div>\n<p>[1] Scottish Drugs Forum. Take-home Naloxone: Reducing Drug Deaths. \u00c0 l\u2019adresse :<a href=\"http:\/\/www.sdf.org.uk\/index.php\/download_file\/view\/132\/108\/\">www.sdf.org.uk\/index.php\/download_file\/view\/132\/108\/<\/a><\/p>\n<\/div>\n<div>\n<p>[2] Buxton, et al., 2012;<cite> <\/cite><cite>Scottish Drugs Forum.<\/cite><\/p>\n<\/div>\n<div>\n<p>[3] National Services Scotland. 2012. <em>National Naloxone Programme Scotland Monitoring Report \u2013 Naloxone Kits Issued in 2011\/12.<\/em> \u00c0 l\u2019adresse : <a href=\"http:\/\/naloxone.org.uk\/index.php\/allresearch\/99-reseach14\">http:\/\/naloxone.org.uk\/index.php\/allresearch\/99-reseach14<\/a><\/p>\n<\/div>\n<div>\n<p>[4] Dasgupta, N. et al. 2008. \u00ab\u00a0Project Lazarus: Overdose Prevention and Responsible Pain Management\u00a0\u00bb. <em>North Carolina Board of Medicine: Forum<\/em>, p. 8. \u00c0 l\u2019adresse :<a href=\"http:\/\/www.ncmedboard.org\/images\/uploads\/publications_uploads\/no108.pdf\">www.ncmedboard.org\/images\/uploads\/publications_uploads\/no108.pdf<\/a><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La naloxone est un compos\u00e9 chimique s\u00e9curitaire et tr\u00e8s efficace qui inverse les effets des opiac\u00e9s comme l\u2019h\u00e9ro\u00efne. Depuis 40 ans, elle est utilis\u00e9e dans des milieux cliniques comme traitement d\u2019urgence contre les surdoses d\u2019opiac\u00e9s. Aux \u00c9.-U. et en Europe, les programmes \u00ab\u00a0Take Home Naloxone\u00a0\u00bb ont \u00e9t\u00e9 associ\u00e9s \u00e0 des r\u00e9ductions de jusqu\u2019\u00e0 34\u00a0% des [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2981,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","footnotes":""},"categories":[7,41,42],"tags":[],"class_list":["post-1318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","category-overdose-fr","category-supervised-consumption-services-fr"],"acf":[],"mb":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Qu\u2019est-ce que la naloxone? - Canadian Drug Policy Coalition<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/webdisk.drugpolicy.ca\/fr\/quest-ce-que-la-naloxone\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qu\u2019est-ce que la naloxone? - Canadian Drug Policy Coalition\" \/>\n<meta property=\"og:description\" content=\"La naloxone est un compos\u00e9 chimique s\u00e9curitaire et tr\u00e8s efficace qui inverse les effets des opiac\u00e9s comme l\u2019h\u00e9ro\u00efne. Depuis 40 ans, elle est utilis\u00e9e dans des milieux cliniques comme traitement d\u2019urgence contre les surdoses d\u2019opiac\u00e9s. Aux \u00c9.-U. et en Europe, les programmes \u00ab\u00a0Take Home Naloxone\u00a0\u00bb ont \u00e9t\u00e9 associ\u00e9s \u00e0 des r\u00e9ductions de jusqu\u2019\u00e0 34\u00a0% des [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/webdisk.drugpolicy.ca\/fr\/quest-ce-que-la-naloxone\/\" \/>\n<meta property=\"og:site_name\" content=\"Canadian Drug Policy Coalition\" \/>\n<meta property=\"article:published_time\" content=\"2012-08-30T18:31:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-04-04T20:23:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.drugpolicy.ca\/wp-content\/uploads\/2015\/01\/CDPC_NaloxoneMultiple_Blog_415x415px-S.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"415\" \/>\n\t<meta property=\"og:image:height\" content=\"415\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/webdisk.drugpolicy.ca\\\/fr\\\/quest-ce-que-la-naloxone\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/webdisk.drugpolicy.ca\\\/fr\\\/quest-ce-que-la-naloxone\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/mail.drugpolicy.ca\\\/fr\\\/#\\\/schema\\\/person\\\/dfa227f7f7fb3d70383391c4c01ec657\"},\"headline\":\"Qu\u2019est-ce que la naloxone?\",\"datePublished\":\"2012-08-30T18:31:31+00:00\",\"dateModified\":\"2015-04-04T20:23:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/webdisk.drugpolicy.ca\\\/fr\\\/quest-ce-que-la-naloxone\\\/\"},\"wordCount\":647,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mail.drugpolicy.ca\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/webdisk.drugpolicy.ca\\\/fr\\\/quest-ce-que-la-naloxone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/webdisk.drugpolicy.ca\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/CDPC_NaloxoneMultiple_Blog_415x415px-S.jpg\",\"articleSection\":[\"Non classifi\u00e9(e)\",\"Overdose\",\"Supervised Consumption Services\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/webdisk.drugpolicy.ca\\\/fr\\\/quest-ce-que-la-naloxone\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/webdisk.drugpolicy.ca\\\/fr\\\/quest-ce-que-la-naloxone\\\/\",\"url\":\"https:\\\/\\\/webdisk.drugpolicy.ca\\\/fr\\\/quest-ce-que-la-naloxone\\\/\",\"name\":\"Qu\u2019est-ce que la naloxone? - Canadian Drug Policy Coalition\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.drugpolicy.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/webdisk.drugpolicy.ca\\\/fr\\\/quest-ce-que-la-naloxone\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/webdisk.drugpolicy.ca\\\/fr\\\/quest-ce-que-la-naloxone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/webdisk.drugpolicy.ca\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/CDPC_NaloxoneMultiple_Blog_415x415px-S.jpg\",\"datePublished\":\"2012-08-30T18:31:31+00:00\",\"dateModified\":\"2015-04-04T20:23:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/webdisk.drugpolicy.ca\\\/fr\\\/quest-ce-que-la-naloxone\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/webdisk.drugpolicy.ca\\\/fr\\\/quest-ce-que-la-naloxone\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/webdisk.drugpolicy.ca\\\/fr\\\/quest-ce-que-la-naloxone\\\/#primaryimage\",\"url\":\"https:\\\/\\\/webdisk.drugpolicy.ca\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/CDPC_NaloxoneMultiple_Blog_415x415px-S.jpg\",\"contentUrl\":\"https:\\\/\\\/webdisk.drugpolicy.ca\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/CDPC_NaloxoneMultiple_Blog_415x415px-S.jpg\",\"width\":415,\"height\":415},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/webdisk.drugpolicy.ca\\\/fr\\\/quest-ce-que-la-naloxone\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mail.drugpolicy.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qu\u2019est-ce que la naloxone?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.drugpolicy.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/mail.drugpolicy.ca\\\/fr\\\/\",\"name\":\"Canadian Drug Policy Coalition\",\"description\":\"Change policy. Save lives.\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.drugpolicy.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.drugpolicy.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.drugpolicy.ca\\\/fr\\\/#organization\",\"name\":\"Canadian Drug Policy Coalition\",\"url\":\"https:\\\/\\\/mail.drugpolicy.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mail.drugpolicy.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/drugpolicy.ca\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/CDPC-logo-white-on-red-150-dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/drugpolicy.ca\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/CDPC-logo-white-on-red-150-dpi.jpg\",\"width\":332,\"height\":333,\"caption\":\"Canadian Drug Policy Coalition\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.drugpolicy.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mail.drugpolicy.ca\\\/fr\\\/#\\\/schema\\\/person\\\/dfa227f7f7fb3d70383391c4c01ec657\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/88091dfe0f7786637ad63cd9bc22390708578b03d96e777d8ad2685d80b777b9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/88091dfe0f7786637ad63cd9bc22390708578b03d96e777d8ad2685d80b777b9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/88091dfe0f7786637ad63cd9bc22390708578b03d96e777d8ad2685d80b777b9?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/webdisk.drugpolicy.ca\\\/fr\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qu\u2019est-ce que la naloxone? - Canadian Drug Policy Coalition","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/webdisk.drugpolicy.ca\/fr\/quest-ce-que-la-naloxone\/","og_locale":"fr_FR","og_type":"article","og_title":"Qu\u2019est-ce que la naloxone? - Canadian Drug Policy Coalition","og_description":"La naloxone est un compos\u00e9 chimique s\u00e9curitaire et tr\u00e8s efficace qui inverse les effets des opiac\u00e9s comme l\u2019h\u00e9ro\u00efne. Depuis 40 ans, elle est utilis\u00e9e dans des milieux cliniques comme traitement d\u2019urgence contre les surdoses d\u2019opiac\u00e9s. Aux \u00c9.-U. et en Europe, les programmes \u00ab\u00a0Take Home Naloxone\u00a0\u00bb ont \u00e9t\u00e9 associ\u00e9s \u00e0 des r\u00e9ductions de jusqu\u2019\u00e0 34\u00a0% des [&hellip;]","og_url":"https:\/\/webdisk.drugpolicy.ca\/fr\/quest-ce-que-la-naloxone\/","og_site_name":"Canadian Drug Policy Coalition","article_published_time":"2012-08-30T18:31:31+00:00","article_modified_time":"2015-04-04T20:23:05+00:00","og_image":[{"width":415,"height":415,"url":"https:\/\/www.drugpolicy.ca\/wp-content\/uploads\/2015\/01\/CDPC_NaloxoneMultiple_Blog_415x415px-S.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/webdisk.drugpolicy.ca\/fr\/quest-ce-que-la-naloxone\/#article","isPartOf":{"@id":"https:\/\/webdisk.drugpolicy.ca\/fr\/quest-ce-que-la-naloxone\/"},"author":{"name":"admin","@id":"https:\/\/mail.drugpolicy.ca\/fr\/#\/schema\/person\/dfa227f7f7fb3d70383391c4c01ec657"},"headline":"Qu\u2019est-ce que la naloxone?","datePublished":"2012-08-30T18:31:31+00:00","dateModified":"2015-04-04T20:23:05+00:00","mainEntityOfPage":{"@id":"https:\/\/webdisk.drugpolicy.ca\/fr\/quest-ce-que-la-naloxone\/"},"wordCount":647,"commentCount":0,"publisher":{"@id":"https:\/\/mail.drugpolicy.ca\/fr\/#organization"},"image":{"@id":"https:\/\/webdisk.drugpolicy.ca\/fr\/quest-ce-que-la-naloxone\/#primaryimage"},"thumbnailUrl":"https:\/\/webdisk.drugpolicy.ca\/wp-content\/uploads\/2015\/01\/CDPC_NaloxoneMultiple_Blog_415x415px-S.jpg","articleSection":["Non classifi\u00e9(e)","Overdose","Supervised Consumption Services"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/webdisk.drugpolicy.ca\/fr\/quest-ce-que-la-naloxone\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/webdisk.drugpolicy.ca\/fr\/quest-ce-que-la-naloxone\/","url":"https:\/\/webdisk.drugpolicy.ca\/fr\/quest-ce-que-la-naloxone\/","name":"Qu\u2019est-ce que la naloxone? - Canadian Drug Policy Coalition","isPartOf":{"@id":"https:\/\/mail.drugpolicy.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/webdisk.drugpolicy.ca\/fr\/quest-ce-que-la-naloxone\/#primaryimage"},"image":{"@id":"https:\/\/webdisk.drugpolicy.ca\/fr\/quest-ce-que-la-naloxone\/#primaryimage"},"thumbnailUrl":"https:\/\/webdisk.drugpolicy.ca\/wp-content\/uploads\/2015\/01\/CDPC_NaloxoneMultiple_Blog_415x415px-S.jpg","datePublished":"2012-08-30T18:31:31+00:00","dateModified":"2015-04-04T20:23:05+00:00","breadcrumb":{"@id":"https:\/\/webdisk.drugpolicy.ca\/fr\/quest-ce-que-la-naloxone\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/webdisk.drugpolicy.ca\/fr\/quest-ce-que-la-naloxone\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/webdisk.drugpolicy.ca\/fr\/quest-ce-que-la-naloxone\/#primaryimage","url":"https:\/\/webdisk.drugpolicy.ca\/wp-content\/uploads\/2015\/01\/CDPC_NaloxoneMultiple_Blog_415x415px-S.jpg","contentUrl":"https:\/\/webdisk.drugpolicy.ca\/wp-content\/uploads\/2015\/01\/CDPC_NaloxoneMultiple_Blog_415x415px-S.jpg","width":415,"height":415},{"@type":"BreadcrumbList","@id":"https:\/\/webdisk.drugpolicy.ca\/fr\/quest-ce-que-la-naloxone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mail.drugpolicy.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Qu\u2019est-ce que la naloxone?"}]},{"@type":"WebSite","@id":"https:\/\/mail.drugpolicy.ca\/fr\/#website","url":"https:\/\/mail.drugpolicy.ca\/fr\/","name":"Canadian Drug Policy Coalition","description":"Change policy. Save lives.","publisher":{"@id":"https:\/\/mail.drugpolicy.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.drugpolicy.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mail.drugpolicy.ca\/fr\/#organization","name":"Canadian Drug Policy Coalition","url":"https:\/\/mail.drugpolicy.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mail.drugpolicy.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/drugpolicy.ca\/wp-content\/uploads\/2019\/04\/CDPC-logo-white-on-red-150-dpi.jpg","contentUrl":"https:\/\/drugpolicy.ca\/wp-content\/uploads\/2019\/04\/CDPC-logo-white-on-red-150-dpi.jpg","width":332,"height":333,"caption":"Canadian Drug Policy Coalition"},"image":{"@id":"https:\/\/mail.drugpolicy.ca\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/mail.drugpolicy.ca\/fr\/#\/schema\/person\/dfa227f7f7fb3d70383391c4c01ec657","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/88091dfe0f7786637ad63cd9bc22390708578b03d96e777d8ad2685d80b777b9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/88091dfe0f7786637ad63cd9bc22390708578b03d96e777d8ad2685d80b777b9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/88091dfe0f7786637ad63cd9bc22390708578b03d96e777d8ad2685d80b777b9?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/webdisk.drugpolicy.ca\/fr\/author\/admin\/"}]}},"mfb_rest_fields":["title","yoast_head","yoast_head_json"],"_links":{"self":[{"href":"https:\/\/webdisk.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/posts\/1318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webdisk.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webdisk.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webdisk.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webdisk.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/comments?post=1318"}],"version-history":[{"count":0,"href":"https:\/\/webdisk.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/posts\/1318\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/webdisk.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/media\/2981"}],"wp:attachment":[{"href":"https:\/\/webdisk.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/media?parent=1318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webdisk.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/categories?post=1318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webdisk.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/tags?post=1318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}